{"id":14798,"date":"2024-03-21T08:40:58","date_gmt":"2024-03-21T07:40:58","guid":{"rendered":"https:\/\/comoacqua.it\/?p=14798"},"modified":"2025-07-08T12:23:32","modified_gmt":"2025-07-08T12:23:32","slug":"team-that-wins-does-not-change-pezzoli-confirmed-president","status":"publish","type":"post","link":"https:\/\/comoacqua.it\/en\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/","title":{"rendered":"A winning team does not change: Pezzoli confirmed as president"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>The 2023 budget approved: once again the Como-based operator presents numbers of absolute excellence. Members renew mandate to board of directors<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como, 20 marzo 2024 \u2013 L\u2019assemblea dei soci di Como Acqua, riunita presso Villa Gallio, ha confermato per acclamazione l\u2019Ing. Enrico Pezzoli nel ruolo di Presidente del CdA del gestore unico del Servizio Idrico Integrato nella provincia comasca. Si tratta del terzo mandato conferito alla figura apicale dell\u2019azienda, che continuer\u00e0 ad essere affiancata da Laura Santin e Alessandro Mogavero, anche loro confermati come membri del Consiglio di Amministrazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il rinnovo della fiducia nei confronti del management \u00e8 la logica conseguenza degli ottimi risultati ottenuti. Il bilancio di esercizio di Como Acqua, contestualmente approvato nella stessa seduta assembleare, ha registrato un valore della produzione pari a 91,141 milioni di euro, in linea con il precedente esercizio, mentre cresce notevolmente l\u2019EBITDA, che nel 2023 si impenna a 13,223 milioni di euro, ovvero 3,669 milioni in pi\u00f9 (+38,4%) rispetto al bilancio 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Particolarmente rilevante \u00e8 la voce degli investimenti, che si attesta a 41,193 milioni di euro. Il dato segna una crescita del 9,3% rispetto ai 37,681 milioni dell\u2019esercizio precedente e si colloca in perfetta coerenza con il piano triennale 2023\/26, che ammonta a oltre 163 milioni di euro, rappresentando un vero proprio benchmark per la capacit\u00e0 di mettere a terra interventi concreti e lungimiranti a beneficio della cittadinanza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNel 2022 la carenza idrica ci ha obbligato a fornire risposte immediate, in piena urgenza\u201d &#8211; spiega l\u2019Ing. Pezzoli &#8211; \u201cOggi, invece, sappiamo bene che la crisi climatica ci accompagner\u00e0 per diverso tempo e che bisogna quindi approntare delle strategie di pi\u00f9 lungo respiro, preparandosi inoltre a fronteggiare il sempre pi\u00f9 frenetico alternarsi tra periodi siccitosi e fasi di precipitazioni anche molto abbondanti. L\u2019unica via consiste nell\u2019attrezzarsi con delle infrastrutture all\u2019altezza\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un impegno decisamente rilevante per il gestore unico, che al 31.12.2023 serve oltre mezzo milione di cittadini in 147 comuni del territorio, frutto di un percorso di aggregazione gestionale che ha visto la societ\u00e0 di riflesso adeguare nel corso del tempo il proprio organico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dalle 151 unit\u00e0 del 2019, primo anno di attivit\u00e0, la forza lavoro \u00e8 cresciuta fino ad arrivare nel 2023 a quota 299 dipendenti. Nell\u2019ultimo anno ci sono stati 28 nuovi ingressi, con un aumento dell\u2019organico del 10% rispetto al 2022, e nuove assunzioni sono gi\u00e0 state programmate per il 2024, con uno sguardo particolare al gender balance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como Acqua ha infatti intrapreso il percorso finalizzato all\u2019ottenimento della parit\u00e0 di genere, partendo da basi davvero ottime: gi\u00e0 oggi, l\u2019organico vede una prevalenza di donne tra gli impiegati (65%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cL\u2019impegno di tutti coloro che mettono le proprie competenze al servizio di Como Acqua e l\u2019unit\u00e0 di intenti che ci lega ai soci sono stati fattori fondamentali nel conseguimento di questi importanti risultati\u201d, commenta l\u2019Ing. Pezzoli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCome previsto a suo tempo, nell\u2019arco di cinque anni la societ\u00e0 \u00e8 cresciuta notevolmente, fino quasi a raggiungere la piena maturazione industriale. Oggi possiamo dire che Como Acqua si \u00e8 dimostrata pienamente all\u2019altezza delle sfide che ha dovuto affrontare in questi anni, nonch\u00e9 pronta per quelle nuove che l\u2019attendono. Viviamo un periodo storico nel quale l\u2019acqua \u00e8 al centro di fondamentali riflessioni che riguardano i cambiamenti climatici e un gestore moderno deve essere capace di mettere in campo soluzioni innovative per fronteggiare i nuovi problemi. Abbiamo dimostrato di essere pronti in vari modi, dalla capacit\u00e0 di utilizzare le opportunit\u00e0 derivanti dal PNRR alla competenza tecnologica che caratterizza il nostro operato quotidiano e che, grazie all\u2019Intelligenza Artificiale, far\u00e0 un ulteriore salto in avanti. Siamo quindi pronti per aprire un nuovo capitolo della storia di Como Acqua, determinati a garantire un servizio di assoluta eccellenza per il nostro territorio, in qualunque frangente\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>Approvato il bilancio 2023: ancora una volta il gestore comasco presenta numeri di assoluta eccellenza. I soci rinnovano il mandato al CdA Como, 20 marzo 2024 \u2013 L\u2019assemblea dei soci di Como Acqua, riunita presso Villa Gallio, ha confermato per acclamazione l\u2019Ing. Enrico Pezzoli nel ruolo di Presidente del CdA del gestore unico del Servizio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[178],"tags":[],"class_list":["post-14798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicati-stampa","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Squadra che vince non si cambia: Pezzoli confermato Presidente | ComoAcqua<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comoacqua.it\/en\/press-releases\/team-that-wins-does-not-change-pezzoli-confirmed-president\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Squadra che vince non si cambia: Pezzoli confermato Presidente | ComoAcqua\" \/>\n<meta property=\"og:description\" content=\"Approvato il bilancio 2023: ancora una volta il gestore comasco presenta numeri di assoluta eccellenza. I soci rinnovano il mandato al CdA Como, 20 marzo 2024 \u2013 L\u2019assemblea dei soci di Como Acqua, riunita presso Villa Gallio, ha confermato per acclamazione l\u2019Ing. Enrico Pezzoli nel ruolo di Presidente del CdA del gestore unico del Servizio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comoacqua.it\/en\/press-releases\/team-that-wins-does-not-change-pezzoli-confirmed-president\/\" \/>\n<meta property=\"og:site_name\" content=\"ComoAcqua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ComoAcquaSrl\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T07:40:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T12:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comoacqua.it\/wp-content\/uploads\/2025\/07\/OG-image_1200x630-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Francesca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/\"},\"author\":{\"name\":\"Francesca\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#\\\/schema\\\/person\\\/b01b84de63809668c26a3845c1ebec10\"},\"headline\":\"Squadra che vince non si cambia: Pezzoli confermato Presidente\",\"datePublished\":\"2024-03-21T07:40:58+00:00\",\"dateModified\":\"2025-07-08T12:23:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/\"},\"wordCount\":613,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Comunicati Stampa\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/\",\"url\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/\",\"name\":\"Squadra che vince non si cambia: Pezzoli confermato Presidente | ComoAcqua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2024-03-21T07:40:58+00:00\",\"dateModified\":\"2025-07-08T12:23:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/comunicati-stampa\\\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comoacqua.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Squadra che vince non si cambia: Pezzoli confermato Presidente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#website\",\"url\":\"https:\\\/\\\/comoacqua.it\\\/\",\"name\":\"Como Acqua\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comoacqua.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#organization\",\"name\":\"Como Acqua\",\"url\":\"https:\\\/\\\/comoacqua.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comoacqua.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/favicon_como_acqua.png\",\"contentUrl\":\"https:\\\/\\\/comoacqua.it\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/favicon_como_acqua.png\",\"width\":500,\"height\":500,\"caption\":\"Como Acqua\"},\"image\":{\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ComoAcquaSrl\",\"https:\\\/\\\/www.instagram.com\\\/comoacqua\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/como-acqua-srl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4_J4Hda70rY_REO8K5Ec8g\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comoacqua.it\\\/#\\\/schema\\\/person\\\/b01b84de63809668c26a3845c1ebec10\",\"name\":\"Francesca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a122407ababb4fe7c485a5093fcff54d997eb8095ded214700caad42d7f422ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a122407ababb4fe7c485a5093fcff54d997eb8095ded214700caad42d7f422ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a122407ababb4fe7c485a5093fcff54d997eb8095ded214700caad42d7f422ea?s=96&d=mm&r=g\",\"caption\":\"Francesca\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A winning team does not change: Pezzoli confirmed as president | ComoAcqua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comoacqua.it\/en\/press-releases\/team-that-wins-does-not-change-pezzoli-confirmed-president\/","og_locale":"en_US","og_type":"article","og_title":"Squadra che vince non si cambia: Pezzoli confermato Presidente | ComoAcqua","og_description":"Approvato il bilancio 2023: ancora una volta il gestore comasco presenta numeri di assoluta eccellenza. I soci rinnovano il mandato al CdA Como, 20 marzo 2024 \u2013 L\u2019assemblea dei soci di Como Acqua, riunita presso Villa Gallio, ha confermato per acclamazione l\u2019Ing. Enrico Pezzoli nel ruolo di Presidente del CdA del gestore unico del Servizio [&hellip;]","og_url":"https:\/\/comoacqua.it\/en\/press-releases\/team-that-wins-does-not-change-pezzoli-confirmed-president\/","og_site_name":"ComoAcqua","article_publisher":"https:\/\/www.facebook.com\/ComoAcquaSrl","article_published_time":"2024-03-21T07:40:58+00:00","article_modified_time":"2025-07-08T12:23:32+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/comoacqua.it\/wp-content\/uploads\/2025\/07\/OG-image_1200x630-1.png","type":"image\/png"}],"author":"Francesca","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Francesca","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/#article","isPartOf":{"@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/"},"author":{"name":"Francesca","@id":"https:\/\/comoacqua.it\/#\/schema\/person\/b01b84de63809668c26a3845c1ebec10"},"headline":"Squadra che vince non si cambia: Pezzoli confermato Presidente","datePublished":"2024-03-21T07:40:58+00:00","dateModified":"2025-07-08T12:23:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/"},"wordCount":613,"commentCount":0,"publisher":{"@id":"https:\/\/comoacqua.it\/#organization"},"image":{"@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/#primaryimage"},"thumbnailUrl":"","articleSection":["Comunicati Stampa"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/","url":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/","name":"A winning team does not change: Pezzoli confirmed as president | ComoAcqua","isPartOf":{"@id":"https:\/\/comoacqua.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/#primaryimage"},"image":{"@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/#primaryimage"},"thumbnailUrl":"","datePublished":"2024-03-21T07:40:58+00:00","dateModified":"2025-07-08T12:23:32+00:00","breadcrumb":{"@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/comoacqua.it\/comunicati-stampa\/squadra-che-vince-non-si-cambia-pezzoli-confermato-presidente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comoacqua.it\/"},{"@type":"ListItem","position":2,"name":"Squadra che vince non si cambia: Pezzoli confermato Presidente"}]},{"@type":"WebSite","@id":"https:\/\/comoacqua.it\/#website","url":"https:\/\/comoacqua.it\/","name":"Como Water","description":"","publisher":{"@id":"https:\/\/comoacqua.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comoacqua.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/comoacqua.it\/#organization","name":"Como Water","url":"https:\/\/comoacqua.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/comoacqua.it\/#\/schema\/logo\/image\/","url":"https:\/\/comoacqua.it\/wp-content\/uploads\/2025\/06\/favicon_como_acqua.png","contentUrl":"https:\/\/comoacqua.it\/wp-content\/uploads\/2025\/06\/favicon_como_acqua.png","width":500,"height":500,"caption":"Como Acqua"},"image":{"@id":"https:\/\/comoacqua.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ComoAcquaSrl","https:\/\/www.instagram.com\/comoacqua\/","https:\/\/www.linkedin.com\/company\/como-acqua-srl\/","https:\/\/www.youtube.com\/channel\/UC4_J4Hda70rY_REO8K5Ec8g"]},{"@type":"Person","@id":"https:\/\/comoacqua.it\/#\/schema\/person\/b01b84de63809668c26a3845c1ebec10","name":"Francesca","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a122407ababb4fe7c485a5093fcff54d997eb8095ded214700caad42d7f422ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a122407ababb4fe7c485a5093fcff54d997eb8095ded214700caad42d7f422ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a122407ababb4fe7c485a5093fcff54d997eb8095ded214700caad42d7f422ea?s=96&d=mm&r=g","caption":"Francesca"}}]}},"_links":{"self":[{"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/posts\/14798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/comments?post=14798"}],"version-history":[{"count":0,"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/posts\/14798\/revisions"}],"wp:attachment":[{"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/media?parent=14798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/categories?post=14798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comoacqua.it\/en\/wp-json\/wp\/v2\/tags?post=14798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}